{"id":690,"date":"2017-12-15T01:11:52","date_gmt":"2017-12-15T01:11:52","guid":{"rendered":"https:\/\/evalart.com\/?p=690"},"modified":"2025-03-20T06:38:50","modified_gmt":"2025-03-20T06:38:50","slug":"pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores","status":"publish","type":"post","link":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/","title":{"rendered":"Pruebas de Programaci\u00f3n en L\u00ednea para Reclutamiento y Selecci\u00f3n de Desarrolladores"},"content":{"rendered":"<p>Los procesos de selecci\u00f3n para evaluar desarrolladores tienden a ser m\u00e1s largos y complejos que para otras profesiones. Una de las dificultades particulares para evaluar candidatos para estas posiciones es asegurar la competencia t\u00e9cnica del candidato. Tradicionalmente se utilizan evaluaciones t\u00e9cnicas escritas, as\u00ed como entrevistas t\u00e9cnicas para este fin. Las entrevistas t\u00e9cnicas son \u00fatiles, pero dado que requieren asignar recursos valiosos para hacerlas, no se pueden aplicar a todos los candidatos. Las pruebas escritas se utilizan entonces para pre filtrar candidatos, pero estas tienden a presentar varios problemas.<\/p>\n<p>Las pruebas escritas para evaluar programadores son en su mayor\u00eda cuestionarios con preguntas para evaluar conocimientos t\u00e9cnicos. El problema con estas pruebas es que son poco efectivas para medir habilidades de programaci\u00f3n. Muchas veces las preguntas requieren saber de memoria comandos o expresiones del lenguaje, lo que puede probar cierta exposici\u00f3n o experiencia con el lenguaje de programaci\u00f3n en particular para el que se eval\u00faa, pero no la destreza con este. De hecho, puede pasar que un programador lleve a\u00f1os trabajando con un lenguaje y sea muy competente, pero no recuerde ciertos comandos dado que no los usa en su d\u00eda a d\u00eda. Es un poco como querer saber si alguien es un buen escritor pregunt\u00e1ndole por definiciones del diccionario al azar.<\/p>\n<p>Una prueba escrita un poco m\u00e1s \u00fatil ser\u00eda aquella donde se pone al candidato en situaciones particulares relevantes relacionados con el trabajo que va a desempe\u00f1ar o donde se le plantea un problema para que lo desarrolle. Sin embargo, la mejor prueba para un programador es una donde deba programar y aunque una prueba escrita podr\u00eda incluir preguntas de este tipo, corregir manualmente el c\u00f3digo escrito por un desarrollador es tedioso y probablemente prohibitivo si se quiere hacer bien y para todos los postulantes.<\/p>\n<p>Es aqu\u00ed donde una herramienta para realizar pruebas de programaci\u00f3n en l\u00ednea puede hacer una gran diferencia. Existen plataformas que permiten que los candidatos a puestos de desarrollador escriban c\u00f3digo y son evaluados autom\u00e1ticamente completamente en l\u00ednea. Por ejemplo, una pregunta puede ser escribir un algoritmo que ordene un arreglo de mayor a menor. La plataforma eval\u00faa el c\u00f3digo escrito por el desarrollador en diversos escenarios y asigna un puntaje. Dado que todo es autom\u00e1tico y en l\u00ednea, es posible evaluar a decenas de candidatos con muy poco esfuerzo y pre filtrar as\u00ed a los mejores. Con este tipo de pruebas es posible reducir un pool de candidatos hasta en un 80%, pudi\u00e9ndose entonces concentrar los esfuerzos en el 20% con mejor rendimiento. Este grupo pre-filtrado puede entonces pasar por el proceso de selecci\u00f3n m\u00e1s tradicional para tomar la decisi\u00f3n final. Aunque el uso de plataformas para aplicar pruebas pr\u00e1cticas de programaci\u00f3n en l\u00ednea a\u00fan no est\u00e1 extendido en Am\u00e9rica Latina, \u00e9stas son muy usadas en Estados Unidos, India y Europa debido a su gran efectividad.<\/p>\n<p><a href=\"\/\/evalart.com\/es\/online-programming-tests\/\">Evalart<\/a> es una de estas plataformas, que cuenta con soporte en espa\u00f1ol (Una de los pocas en el mercado de habla hispana que lo ofrece) y en ingl\u00e9s. Es posible probarla gratis por un mes hasta 10 evaluaciones e incluye tambi\u00e9n otro tipo de prueba \u00fatiles durante los procesos de selecci\u00f3n (tests de ingl\u00e9s, personalidad, liderazgo, Scrum, entre otros). Si desea probar Evalart gratis por un mes puede hacerlo ahora siguiendo este link: <strong><a href=\"\/\/evalart.com\/es\/free-trial\/\">Pruebe Evalart Gratis por un Mes<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Los procesos de selecci\u00f3n para evaluar desarrolladores tienden a ser m\u00e1s largos y complejos que para otras profesiones. Una de las dificultades particulares para evaluar candidatos para estas posiciones es asegurar la competencia t\u00e9cnica del candidato. Tradicionalmente se utilizan evaluaciones t\u00e9cnicas escritas, as\u00ed como entrevistas t\u00e9cnicas para este fin. Las entrevistas t\u00e9cnicas son \u00fatiles, pero [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[43,44],"tags":[],"class_list":["post-690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reclutamiento-ti","category-tcnicas-de-seleccin-de-personal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pruebas de Programaci\u00f3n en L\u00ednea para Reclutamiento y Selecci\u00f3n de Desarrolladores<\/title>\n<meta name=\"description\" content=\"Las Pruebas de Programaci\u00f3n en L\u00ednea permiten ahorrar tiempo y dinero en procesos de selecci\u00f3n donde se buscan programadores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pruebas de Programaci\u00f3n en L\u00ednea para Reclutamiento y Selecci\u00f3n de Desarrolladores\" \/>\n<meta property=\"og:description\" content=\"Las Pruebas de Programaci\u00f3n en L\u00ednea permiten ahorrar tiempo y dinero en procesos de selecci\u00f3n donde se buscan programadores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/\" \/>\n<meta property=\"og:site_name\" content=\"Evalart\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-15T01:11:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-20T06:38:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evalart.com\/wp-content\/uploads\/2017\/12\/EvalartProgTestScreen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aradelsy Burgos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aradelsy Burgos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\\\/\"},\"author\":{\"name\":\"Aradelsy Burgos\",\"@id\":\"https:\\\/\\\/evalart.com\\\/pb\\\/#\\\/schema\\\/person\\\/93f496c3a4af2076e61af63c9b21bc4a\"},\"headline\":\"Pruebas de Programaci\u00f3n en L\u00ednea para Reclutamiento y Selecci\u00f3n de Desarrolladores\",\"datePublished\":\"2017-12-15T01:11:52+00:00\",\"dateModified\":\"2025-03-20T06:38:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\\\/\"},\"wordCount\":1601,\"publisher\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/pb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/evalart.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/EvalartProgTestScreen.jpg\",\"articleSection\":[\"Reclutamiento TI\",\"T\u00e9cnicas de Selecci\u00f3n de Personal\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\\\/\",\"url\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\\\/\",\"name\":\"Pruebas de Programaci\u00f3n en L\u00ednea para Reclutamiento y Selecci\u00f3n de Desarrolladores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/evalart.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/EvalartProgTestScreen.jpg\",\"datePublished\":\"2017-12-15T01:11:52+00:00\",\"dateModified\":\"2025-03-20T06:38:50+00:00\",\"description\":\"Las Pruebas de Programaci\u00f3n en L\u00ednea permiten ahorrar tiempo y dinero en procesos de selecci\u00f3n donde se buscan programadores.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/evalart.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/EvalartProgTestScreen.jpg\",\"contentUrl\":\"https:\\\/\\\/evalart.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/EvalartProgTestScreen.jpg\",\"width\":660,\"height\":372,\"caption\":\"Prueba de Programacion en L\u00ednea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/evalart.com\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pruebas de Programaci\u00f3n en L\u00ednea para Reclutamiento y Selecci\u00f3n de Desarrolladores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/evalart.com\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/evalart.com\\\/pb\\\/\",\"name\":\"Evalart\",\"description\":\"Skills Assessment Platform for your Recruiting Process\",\"publisher\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/pb\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/evalart.com\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/evalart.com\\\/pb\\\/#organization\",\"name\":\"Evalart\",\"url\":\"https:\\\/\\\/evalart.com\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/evalart.com\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/evalart.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/evalart-logo.svg\",\"contentUrl\":\"https:\\\/\\\/evalart.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/evalart-logo.svg\",\"caption\":\"Evalart\"},\"image\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/evalart.com\\\/pb\\\/#\\\/schema\\\/person\\\/93f496c3a4af2076e61af63c9b21bc4a\",\"name\":\"Aradelsy Burgos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/evalart.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/IMG_0083-e1756824836220-150x150.jpg\",\"url\":\"https:\\\/\\\/evalart.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/IMG_0083-e1756824836220-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/evalart.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/IMG_0083-e1756824836220-150x150.jpg\",\"caption\":\"Aradelsy Burgos\"},\"description\":\"Aradelsy Burgos is the General Manager of Evalart, leading the company\u2019s strategy and growth in the online assessments space. With experience building and scaling SaaS products, she focuses on enhancing recruitment processes through innovative technologies and evaluations. Beyond product development, she works closely with clients across Latin America to understand their hiring challenges and translate those needs into platform improvements. Find me on LinkedIn.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/aradelsy-jocelyne-burgos-cota\\\/\"],\"url\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/author\\\/evalart\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pruebas de Programaci\u00f3n en L\u00ednea para Reclutamiento y Selecci\u00f3n de Desarrolladores","description":"Las Pruebas de Programaci\u00f3n en L\u00ednea permiten ahorrar tiempo y dinero en procesos de selecci\u00f3n donde se buscan programadores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/","og_locale":"es_ES","og_type":"article","og_title":"Pruebas de Programaci\u00f3n en L\u00ednea para Reclutamiento y Selecci\u00f3n de Desarrolladores","og_description":"Las Pruebas de Programaci\u00f3n en L\u00ednea permiten ahorrar tiempo y dinero en procesos de selecci\u00f3n donde se buscan programadores.","og_url":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/","og_site_name":"Evalart","article_published_time":"2017-12-15T01:11:52+00:00","article_modified_time":"2025-03-20T06:38:50+00:00","og_image":[{"width":660,"height":372,"url":"https:\/\/evalart.com\/wp-content\/uploads\/2017\/12\/EvalartProgTestScreen.jpg","type":"image\/jpeg"}],"author":"Aradelsy Burgos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Aradelsy Burgos","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/#article","isPartOf":{"@id":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/"},"author":{"name":"Aradelsy Burgos","@id":"https:\/\/evalart.com\/pb\/#\/schema\/person\/93f496c3a4af2076e61af63c9b21bc4a"},"headline":"Pruebas de Programaci\u00f3n en L\u00ednea para Reclutamiento y Selecci\u00f3n de Desarrolladores","datePublished":"2017-12-15T01:11:52+00:00","dateModified":"2025-03-20T06:38:50+00:00","mainEntityOfPage":{"@id":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/"},"wordCount":1601,"publisher":{"@id":"https:\/\/evalart.com\/pb\/#organization"},"image":{"@id":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/#primaryimage"},"thumbnailUrl":"https:\/\/evalart.com\/wp-content\/uploads\/2017\/12\/EvalartProgTestScreen.jpg","articleSection":["Reclutamiento TI","T\u00e9cnicas de Selecci\u00f3n de Personal"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/","url":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/","name":"Pruebas de Programaci\u00f3n en L\u00ednea para Reclutamiento y Selecci\u00f3n de Desarrolladores","isPartOf":{"@id":"https:\/\/evalart.com\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/#primaryimage"},"image":{"@id":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/#primaryimage"},"thumbnailUrl":"https:\/\/evalart.com\/wp-content\/uploads\/2017\/12\/EvalartProgTestScreen.jpg","datePublished":"2017-12-15T01:11:52+00:00","dateModified":"2025-03-20T06:38:50+00:00","description":"Las Pruebas de Programaci\u00f3n en L\u00ednea permiten ahorrar tiempo y dinero en procesos de selecci\u00f3n donde se buscan programadores.","breadcrumb":{"@id":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/#primaryimage","url":"https:\/\/evalart.com\/wp-content\/uploads\/2017\/12\/EvalartProgTestScreen.jpg","contentUrl":"https:\/\/evalart.com\/wp-content\/uploads\/2017\/12\/EvalartProgTestScreen.jpg","width":660,"height":372,"caption":"Prueba de Programacion en L\u00ednea"},{"@type":"BreadcrumbList","@id":"https:\/\/evalart.com\/es\/blog\/pruebas-de-programacion-en-linea-para-reclutamiento-y-seleccion-de-desarrolladores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/evalart.com\/pb\/"},{"@type":"ListItem","position":2,"name":"Pruebas de Programaci\u00f3n en L\u00ednea para Reclutamiento y Selecci\u00f3n de Desarrolladores"}]},{"@type":"WebSite","@id":"https:\/\/evalart.com\/pb\/#website","url":"https:\/\/evalart.com\/pb\/","name":"Evalart","description":"Skills Assessment Platform for your Recruiting Process","publisher":{"@id":"https:\/\/evalart.com\/pb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evalart.com\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/evalart.com\/pb\/#organization","name":"Evalart","url":"https:\/\/evalart.com\/pb\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/evalart.com\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/evalart.com\/wp-content\/uploads\/2024\/03\/evalart-logo.svg","contentUrl":"https:\/\/evalart.com\/wp-content\/uploads\/2024\/03\/evalart-logo.svg","caption":"Evalart"},"image":{"@id":"https:\/\/evalart.com\/pb\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/evalart.com\/pb\/#\/schema\/person\/93f496c3a4af2076e61af63c9b21bc4a","name":"Aradelsy Burgos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/evalart.com\/wp-content\/uploads\/2025\/09\/IMG_0083-e1756824836220-150x150.jpg","url":"https:\/\/evalart.com\/wp-content\/uploads\/2025\/09\/IMG_0083-e1756824836220-150x150.jpg","contentUrl":"https:\/\/evalart.com\/wp-content\/uploads\/2025\/09\/IMG_0083-e1756824836220-150x150.jpg","caption":"Aradelsy Burgos"},"description":"Aradelsy Burgos is the General Manager of Evalart, leading the company\u2019s strategy and growth in the online assessments space. With experience building and scaling SaaS products, she focuses on enhancing recruitment processes through innovative technologies and evaluations. Beyond product development, she works closely with clients across Latin America to understand their hiring challenges and translate those needs into platform improvements. Find me on LinkedIn.","sameAs":["https:\/\/www.linkedin.com\/in\/aradelsy-jocelyne-burgos-cota\/"],"url":"https:\/\/evalart.com\/es\/blog\/author\/evalart\/"}]}},"_links":{"self":[{"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/posts\/690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/comments?post=690"}],"version-history":[{"count":14,"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/posts\/690\/revisions"}],"predecessor-version":[{"id":2295,"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/posts\/690\/revisions\/2295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/media\/747"}],"wp:attachment":[{"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/media?parent=690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/categories?post=690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/tags?post=690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}