{"id":6636,"date":"2020-03-14T01:23:34","date_gmt":"2020-03-14T01:23:34","guid":{"rendered":"https:\/\/evalart.com\/blog\/ufaqs\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\/"},"modified":"2026-07-18T18:57:01","modified_gmt":"2026-07-18T18:57:01","slug":"como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste","status":"publish","type":"ufaq","link":"https:\/\/evalart.com\/es\/blog\/ufaqs\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\/","title":{"rendered":"Como usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste?"},"content":{"rendered":"<style>.ewd-ufaq-post-margin-symbol { border-width: 1px !important; }.ewd-ufaq-faq-title .ewd-ufaq-post-margin-symbol span { font-size: 20px !important; }div.ewd-ufaq-faq-post p { margin: 0 4cm 0 1cm !important; }div.ewd-ufaq-faq-post p {\r\n  margin: 0 0 15px !important;\r\n}\r\n\r\n.np-pricing-ufaqs-container #ewd-ufaq-faq-list {\r\n    background-color: #ffffff;\r\n    border-radius: 16px;\r\n    border: 1px solid #E3E7ED;\r\n    padding: 0;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-div {\r\n    border: none !important;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-title-text h4 {\r\n    color: #222222CC;\r\n    font-size: 18px;\r\n    font-weight: 500;\r\n    line-height: 100%\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-body p {\r\n    color: #77787B;\r\n    font-size: 16px;\r\n    font-weight: 400;\r\n    line-height: 20px;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-category-title {\r\n    display: none;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-category-inner {\r\n    margin: 0;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-category-inner .ewd-ufaq-faq-div {\r\n    border-bottom: 1px solid #E3E7ED !important;\r\n    padding: 1.5rem !important;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-category-inner .ewd-ufaq-faq-div:last-child {\r\n    border-bottom: none !important;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-category {\r\n    margin: 0px;\r\n}<\/style><div  class=\"ewd-ufaq-faq-list ewd-ufaq-page-type-load_more ewd-ufaq-category-tabs-\" id='ewd-ufaq-faq-list'>\n\n\t<input type='hidden' name='show_on_load' value='' id='ewd-ufaq-show-on-load' \/>\n<input type='hidden' name='include_category' value='' id='ewd-ufaq-include-category' \/>\n<input type='hidden' name='exclude_category' value='' id='ewd-ufaq-exclude-category' \/>\n<input type='hidden' name='orderby' value='date' id='ewd-ufaq-orderby' \/>\n<input type='hidden' name='order' value='asc' id='ewd-ufaq-order' \/>\n<input type='hidden' name='post_count' value='-1' id='ewd-ufaq-post-count' \/>\n<input type='hidden' name='current_url' value='\/es\/wp-json\/wp\/v2\/ufaq\/6636' id='ewd-ufaq-current-url' \/>\n\t\n\t\n\t<div class='ewd-ufaq-faqs'>\n\n\t\t<div  class=\"ewd-ufaq-faq-div ewd-ufaq-faq-column-count-one ewd-ufaq-faq-responsive-columns- ewd-ufaq-faq-display-style-one ewd-ufaq-can-be-toggled\" id='ewd-ufaq-post-6636-NpaFWoopQ2' data-post_id='6636'>\n\n\t\t\n\t<div class='ewd-ufaq-faq-title ewd-ufaq-faq-toggle'>\n\t\n\t<a class='ewd-ufaq-post-margin'  href='#' role=\"button\">\n\n\t\t<div class='ewd-ufaq-post-margin-symbol ewd-ufaq-square'>\n\t\t\t<span >A<\/span>\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-faq-title-text'>\n\n\t\t\t<h4>\n\t\t\t\tComo usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste?\t\t\t<\/h4>\n\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-clear'><\/div>\n\n\t<\/a>\n\t\n<\/div>\n\t\n\t<div class='ewd-ufaq-faq-body' >\n\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-post-margin ewd-ufaq-faq-post'>\n\t<p>Evalart le permite agregar el logo de su empresa mediante la opci\u00f3n \u201cpersonalizaci\u00f3n de la cuenta\u201d. All\u00ed puede cambiar el logo que aparece en el men\u00fa del m\u00f3dulo administrador, en las pruebas y en los reportes, as\u00ed como otras configuraciones como colores de fondo y de letras. Para hacer esto siga los pasos descritos a continuaci\u00f3n:  <\/p>\n<ol>\n<li>Despliegue el listado de opciones para el men\u00fa \u201cusuario\u201d ubicado en el men\u00fa principal y seleccione la opci\u00f3n \u201cpersonalizaci\u00f3n de la cuenta\u201d.<br \/>\nSi ya posee un registro creado, hacer clic en el bot\u00f3n del l\u00e1piz ubicado a la derecha. Si a\u00fan no posee ning\u00fan registro, cree uno haciendo clic en el bot\u00f3n \u201cnuevo\u201d ubicado en la esquina superior derecha, para crear un nuevo perfil de personalizaci\u00f3n. <\/li>\n<li>Dir\u00edjase al campo \u201clogotipo\u201d, cargue el logo de su empresa desde la galer\u00eda o archivos locales, ajuste la posici\u00f3n en el campo \u201cposici\u00f3n de logo\u201d y, si lo desea, tambi\u00e9n puede cambiar el color del fondo del logo en el campo \u201cpruebas: color de fondo\u201d (esta opci\u00f3n cambiar\u00e1 \u00fanicamente el color de fondo del encabezado).<\/li>\n<li>Guarde los cambios.<\/li>\n<\/ol>\n<p><strong>NOTA: <\/strong>para cargar archivos desde la galer\u00eda de Evalart, \u00e9stos deben ser cargados a la galer\u00eda antes siguiendo los pasos descritos a continuaci\u00f3n:<\/p>\n<ol>\n<li>En el men\u00fa principal, despliegue las opciones para \u201cconfiguraci\u00f3n\u201d y seleccione \u201cadministrar galer\u00eda\u201d.<\/li>\n<li>Haga clic en el bot\u00f3n \u201cbrowse\u2026\u201d para seleccionar una imagen de los archivos locales.<\/li>\n<li>Ubique el archivo de imagen que desea cargar y seleccionelo.<\/li>\n<li>Haga clic en el bot\u00f3n de \u201cupload\u201d para terminar de cargar la imagen a la galer\u00eda.<\/li>\n<\/ol>\n<\/div>\n\t\t\n\t\t\t<div class='ewd-ufaq-faq-custom-fields'>\n\n\t\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t<\/div>\n\n<\/div>\n\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A Como usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste? Evalart le permite agregar el logo de su empresa mediante la opci\u00f3n \u201cpersonalizaci\u00f3n de la cuenta\u201d. All\u00ed puede cambiar el logo que aparece en el men\u00fa del m\u00f3dulo administrador, en las pruebas y en los reportes, as\u00ed como otras configuraciones como colores de [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"template":"","ufaq-category":[51],"ufaq-tag":[],"class_list":["post-6636","ufaq","type-ufaq","status-publish","hentry","ufaq-category-preguntas-frecuentes-configuracion-y-personalizacion-de-la-cuenta"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste? - Evalart<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste? - Evalart\" \/>\n<meta property=\"og:description\" content=\"A Como usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste? Evalart le permite agregar el logo de su empresa mediante la opci\u00f3n \u201cpersonalizaci\u00f3n de la cuenta\u201d. All\u00ed puede cambiar el logo que aparece en el men\u00fa del m\u00f3dulo administrador, en las pruebas y en los reportes, as\u00ed como otras configuraciones como colores de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evalart.com\/es\/blog\/ufaqs\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\/\" \/>\n<meta property=\"og:site_name\" content=\"Evalart\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-18T18:57:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/ufaqs\\\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\\\/\",\"url\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/ufaqs\\\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\\\/\",\"name\":\"Como usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste? - Evalart\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/#website\"},\"datePublished\":\"2020-03-14T01:23:34+00:00\",\"dateModified\":\"2026-07-18T18:57:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/ufaqs\\\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/ufaqs\\\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/ufaqs\\\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/evalart.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\\\/\\\/evalart.com\\\/es\\\/blog\\\/ufaqs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/evalart.com\\\/es\\\/\",\"name\":\"Evalart\",\"description\":\"Plataforma de evaluaci\u00f3n de habilidades para su proceso de reclutamiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/evalart.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/#organization\",\"name\":\"Evalart\",\"url\":\"https:\\\/\\\/evalart.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/evalart.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/evalart-logo.svg\",\"contentUrl\":\"https:\\\/\\\/evalart.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/evalart-logo.svg\",\"caption\":\"Evalart\"},\"image\":{\"@id\":\"https:\\\/\\\/evalart.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"foundingDate\":\"2017\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/evalart\\\/\",\"https:\\\/\\\/www.g2.com\\\/products\\\/evalart\\\/reviews\",\"https:\\\/\\\/www.capterra.com\\\/p\\\/211129\\\/Evalart\\\/\",\"https:\\\/\\\/www.getapp.com\\\/hr-employee-management-software\\\/a\\\/evalart\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste? - Evalart","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Como usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste? - Evalart","og_description":"A Como usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste? Evalart le permite agregar el logo de su empresa mediante la opci\u00f3n \u201cpersonalizaci\u00f3n de la cuenta\u201d. All\u00ed puede cambiar el logo que aparece en el men\u00fa del m\u00f3dulo administrador, en las pruebas y en los reportes, as\u00ed como otras configuraciones como colores de [&hellip;]","og_url":"https:\/\/evalart.com\/es\/blog\/ufaqs\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\/","og_site_name":"Evalart","article_modified_time":"2026-07-18T18:57:01+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/evalart.com\/es\/blog\/ufaqs\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\/","url":"https:\/\/evalart.com\/es\/blog\/ufaqs\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\/","name":"Como usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste? - Evalart","isPartOf":{"@id":"https:\/\/evalart.com\/es\/#website"},"datePublished":"2020-03-14T01:23:34+00:00","dateModified":"2026-07-18T18:57:01+00:00","breadcrumb":{"@id":"https:\/\/evalart.com\/es\/blog\/ufaqs\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evalart.com\/es\/blog\/ufaqs\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/evalart.com\/es\/blog\/ufaqs\/como-usar-minha-logomarca-nos-relatorios-e-na-execucao-do-teste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/evalart.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"FAQs","item":"https:\/\/evalart.com\/es\/blog\/ufaqs\/"},{"@type":"ListItem","position":3,"name":"Como usar minha logomarca nos relat\u00f3rios e na execu\u00e7\u00e3o do teste?"}]},{"@type":"WebSite","@id":"https:\/\/evalart.com\/es\/#website","url":"https:\/\/evalart.com\/es\/","name":"Evalart","description":"Plataforma de evaluaci\u00f3n de habilidades para su proceso de reclutamiento","publisher":{"@id":"https:\/\/evalart.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evalart.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/evalart.com\/es\/#organization","name":"Evalart","url":"https:\/\/evalart.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/evalart.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/evalart.com\/wp-content\/uploads\/2024\/03\/evalart-logo.svg","contentUrl":"https:\/\/evalart.com\/wp-content\/uploads\/2024\/03\/evalart-logo.svg","caption":"Evalart"},"image":{"@id":"https:\/\/evalart.com\/es\/#\/schema\/logo\/image\/"},"foundingDate":"2017","sameAs":["https:\/\/www.linkedin.com\/company\/evalart\/","https:\/\/www.g2.com\/products\/evalart\/reviews","https:\/\/www.capterra.com\/p\/211129\/Evalart\/","https:\/\/www.getapp.com\/hr-employee-management-software\/a\/evalart\/"]}]}},"_links":{"self":[{"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/ufaq\/6636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/ufaq"}],"about":[{"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/types\/ufaq"}],"author":[{"embeddable":true,"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/users\/18"}],"wp:attachment":[{"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/media?parent=6636"}],"wp:term":[{"taxonomy":"ufaq-category","embeddable":true,"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/ufaq-category?post=6636"},{"taxonomy":"ufaq-tag","embeddable":true,"href":"https:\/\/evalart.com\/es\/wp-json\/wp\/v2\/ufaq-tag?post=6636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}